{"id":2428,"date":"2017-11-23T12:18:51","date_gmt":"2017-11-23T12:18:51","guid":{"rendered":"http:\/\/www.encontrabelohorizonte.com.br\/sobre\/?p=2428"},"modified":"2019-04-12T18:31:04","modified_gmt":"2019-04-12T18:31:04","slug":"gontijo-belo-horizonte","status":"publish","type":"post","link":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/gontijo-belo-horizonte\/","title":{"rendered":"Gontijo Belo Horizonte"},"content":{"rendered":"<div class=\"2e083cf0b19e2c11948dc6ac054ba979\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Com in\u00edcio em 1943, a Via\u00e7\u00e3o<strong> Gontijo\u00a0Belo Horizonte<\/strong> foi fundada por um jovem sonhador e empreendedor, no interior de Minas Gerais. Ab\u00edlio Gontijo, com apenas 19 anos, conduzia uma jardineira pelas estradas prec\u00e1rias da \u00e9poca, atuando tamb\u00e9m como trocador e mec\u00e2nico.<\/p>\n<p>Superando os obst\u00e1culos do caminho, a d\u00e9cada seguinte foi marcada pelo crescimento da empresa, que contou com o avan\u00e7o da ind\u00fastria automobil\u00edstica e rodovi\u00e1ria no pa\u00eds, chegando junto com a industrializa\u00e7\u00e3o do Brasil na d\u00e9cada de 1950.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2429 size-full\" title=\"Gontijo Belo Horizonte\" src=\"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-content\/uploads\/gontijo-bel-horizonte.jpg\" alt=\"Gontijo Belo Horizonte\" width=\"680\" height=\"189\" srcset=\"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-content\/uploads\/gontijo-bel-horizonte.jpg 680w, https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-content\/uploads\/gontijo-bel-horizonte-300x83.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>Na mesma \u00e9poca, <span style=\"text-decoration: underline;\">Ab\u00edlio Gontijo<\/span> tamb\u00e9m incluiu algumas rotas que ligavam cidades menores \u00e0 capital <span style=\"text-decoration: underline;\">Belo Horizonte.<\/span><\/p>\n<p>Atualmente, a empresa transporta anualmente cerca de <span style=\"text-decoration: underline;\">5 milh\u00f5es de passageiros<\/span>. Com uma frota de 1500 ve\u00edculos, a companhia preza principalmente por oferecer servi\u00e7o de qualidade e profissionais qualificados, garantindo conforto e seguran\u00e7a nas viagens rodovi\u00e1rias.<\/p>\n<h3>Endere\u00e7o e Telefone Gontijo Belo Horizonte<\/h3>\n<ul>\n<li><strong>Centro<\/strong> &#8211; Pra\u00e7a Rio Branco, 100 &#8211; Centro &#8211; (31) 3419-1299<\/li>\n<li><strong>Engenho Nogueira<\/strong> &#8211; Rua Professor Jos\u00e9 Vieira de Mendon\u00e7a, 475 &#8211; (31) 3419-1100<\/li>\n<\/ul>\n<h4>Outras informa\u00e7\u00f5es e site<\/h4>\n<ul>\n<li>Mais informa\u00e7\u00f5es: <a href=\"http:\/\/www.gontijo.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">www.gontijo.com.br<\/a><\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o Centro<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3751.2189790214493!2d-43.94287768508578!3d-19.915174986611966!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xa699fc2559acb70x847f2bdf65bbbd!2sPraa+Rio+Branco+100+-+Centro+Belo+Horizonte+-+MG+30111-050!5e0!3m2!1spt-BR!2sbr!4v1511381643813\"><img decoding=\"async\" src=\"http:\/\/www.encontrabelohorizonte.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Com in\u00edcio em 1943, a Via\u00e7\u00e3o Gontijo\u00a0Belo Horizonte foi fundada por um jovem sonhador e empreendedor, no interior de Minas Gerais. Ab\u00edlio Gontijo, com apenas 19 anos, conduzia uma jardineira pelas estradas prec\u00e1rias da \u00e9poca, atuando tamb\u00e9m como trocador e mec\u00e2nico. Superando os obst\u00e1culos do caminho, a d\u00e9cada seguinte foi marcada pelo crescimento da empresa, que contou com o avan\u00e7o da ind\u00fastria automobil\u00edstica e rodovi\u00e1ria no pa\u00eds, chegando junto com a industrializa\u00e7\u00e3o do Brasil na d\u00e9cada de 1950. Na mesma \u00e9poca, Ab\u00edlio Gontijo tamb\u00e9m incluiu algumas rotas que ligavam cidades menores \u00e0 capital Belo Horizonte. Atualmente, a empresa transporta anualmente <\/p>\n","protected":false},"author":1,"featured_media":2429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicos","has_thumb"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=2428"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/media\/2429"}],"wp:attachment":[{"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=2428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=2428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabelohorizonte.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=2428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}